{"id":3388,"date":"2023-03-02T11:54:38","date_gmt":"2023-03-02T16:54:38","guid":{"rendered":"https:\/\/vls.ecampusontario.ca\/dx\/"},"modified":"2024-12-11T14:59:19","modified_gmt":"2024-12-11T19:59:19","slug":"dx","status":"publish","type":"page","link":"https:\/\/vls.ecampusontario.ca\/fr\/dx\/","title":{"rendered":"Faites progresser votre transformation num\u00e9rique"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#1E1A34&Prime; background_image=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/Dx-Banner.png\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb background_position=\u00a0\u00bbcenter_right\u00a0\u00bb custom_padding=\u00a0\u00bb100px||100px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb40px||40px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb40px||40px||true|false\u00a0\u00bb background_color_phone=\u00a0\u00bb#1E1A34&Prime; background_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb background_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb background_enable_image_phone=\u00a0\u00bboff\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb3fd8a6b7-d7cc-48e7-b42d-414e64db3f80&Prime; header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb42px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.1em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: left;\">Faites progresser votre<br \/>\ntransformation<br \/>\nnum\u00e9rique<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#c8d5dd\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb55b77ebb-b59f-4f8d-b74f-86272540b1a2&Prime; text_font_size=\u00a0\u00bb30px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_padding=\u00a0\u00bb2px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Lib\u00e9rez le potentiel de vos priorit\u00e9s en mati\u00e8re d\u2019apprentissage num\u00e9rique avec l\u2019aide d\u2019eCampusOntario. L\u2019avenir de l\u2019apprentissage num\u00e9rique est \u00e0 nos portes. Innovez gr\u00e2ce aux ressources gratuites offertes par eCampusOntario.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb25px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Les \u00e9tablissements d\u2019enseignement sup\u00e9rieur de l\u2019Ontario ont r\u00e9agi d\u00e8s le d\u00e9but de la pand\u00e9mie en passant des salles de classe en personne \u00e0 l\u2019apprentissage \u00e0 distance. Aujourd\u2019hui, les membres d\u2019eCampusOntario travaillent en collaboration pour introduire intentionnellement des innovations qui<br \/>red\u00e9finissent notre fa\u00e7on d\u2019enseigner et d\u2019apprendre.<\/p>\n<p>Les membres d\u2019eCampusOntario collaborent, apprennent les uns des autres et mettent en commun leurs meilleures pratiques, acc\u00e9l\u00e9rant ainsi l\u2019\u00e9laboration d\u2019exp\u00e9riences d\u2019apprentissage num\u00e9rique passionnantes qui font appel \u00e0 de nouvelles ressources, \u00e0 de nouveaux services et \u00e0 de nouveaux programmes afin d\u2019autonomiser les dipl\u00f4m\u00e9s de l\u2019Ontario, c.-\u00e0-d. la main-d\u2019oeuvre de demain.<\/p>\n<p><strong>De quelle fa\u00e7on explorerez-vous le chemin de la transformation num\u00e9rique?<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Lib\u00e9rez le potentiel de vos priorit\u00e9s en mati\u00e8re d\u2019apprentissage num\u00e9rique. Communiquez avec eCampusOntario afin de :<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li style=\"margin-bottom: 15px;\"><span style=\"color: #000000;\"><a href=\"#oer\" style=\"color: #000000;\"><span style=\"text-decoration: underline;\">bonifier vos choix d\u2019apprentissage num\u00e9rique avec les ressources \u00e9ducatives libres (REL) de notre biblioth\u00e8que libre;<\/span><\/a><\/span><\/li>\n<li style=\"margin-bottom: 15px;\"><span style=\"text-decoration: underline; color: #000000;\"><a href=\"#pd\" style=\"color: #000000; text-decoration: underline;\">stimuler vos \u00e9quipes acad\u00e9miques \u00e0 l\u2019aide d\u2019un perfectionnement professionnel pour les chefs de file du domaine num\u00e9rique du 21e si\u00e8cle;<\/a><\/span><\/li>\n<li style=\"margin-bottom: 15px;\"><span style=\"color: #000000;\"><a href=\"#dfg\" style=\"color: #000000;\"><span style=\"text-decoration: underline;\">faire votre choix parmi une gamme de produits, de services et de plateformes pr\u00e9sent\u00e9s dans nos guide de la transformation num\u00e9rique.(Dx) Guides.<\/span><\/a><\/span><\/li>\n<li><span style=\"color: #000000;\"><a href=\"#discover\" style=\"color: #000000;\"><span style=\"text-decoration: underline;\">collaborer dans des environnements d\u2019essai s\u00fbrs pour d\u00e9couvrir, mettre \u00e0 l\u2019essai, \u00e9valuer et adopter des technologies \u00e9ducatives.<\/span><\/a><\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#1E1A34&Prime; custom_padding=\u00a0\u00bb25px||25px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_color=\u00a0\u00bb#FCB53B\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Faites progresser vos ambitions num\u00e9riques. Explorez les ressources gratuites offertes par eCampusOntario.<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb module_id=\u00a0\u00bbdfg\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#657d25&Prime; custom_padding=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb da_popup_slug=\u00a0\u00bbdfg\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||justify-content: center;||align-items:stretch;||flex-direction:column;||@media only screen and (min-width: 768px) {flex-direction:row;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;||    justify-content: center;||    align-items: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/Dx-Logo-icon.png\u00a0\u00bb title_text=\u00a0\u00bbDx Logo-icon\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Explorez nos guide de la transformation num\u00e9rique<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(205,201,206,0.1)\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Explorez le chemin de la transformation num\u00e9rique avec eCampusOntario.<\/strong><br \/>Explorez la gamme compl\u00e8te de programmes d\u2019eCampusOntario dans nos guide de la transformation num\u00e9rique. Choisissez parmi six guides pour faire progresser lespriorit\u00e9s num\u00e9riques de vos champions:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_6,1_6,1_6,1_6,1_6,1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Explore-Digital-Futures-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color: #000;\"><strong>Explorer les perspectives num\u00e9riques<\/strong><\/a><\/span><br \/>Concevez de mani\u00e8re participative la transformation de l\u2019enseignement sup\u00e9rieur<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr2.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Empower-Leaders-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color:#000;\"><strong>Donner aux chefs de file du domaine num\u00e9rique les moyens d\u2019agir<\/strong><\/a><\/span><br \/>\nImpliquez les \u00e9quipes p\u00e9dagogiques dans le perfectionnement professionnel<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr3.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr3&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Investigate-Tech-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color:#000;\"><strong>\u00c9tudier les technologies num\u00e9riques<\/strong><\/a><\/span><br \/>\nD\u00e9couvrez, mettez \u00e0 l\u2019essai, \u00e9valuez et adoptez les technologies \u00e9ducatives<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr4.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Find-Strategic-Partners-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color:#000;\"><strong>Trouver des partenaires strat\u00e9giques<\/strong><\/a><\/span><br \/>\nRenforcez les capacit\u00e9s de vos partenaires et acc\u00e9dez \u00e0 de nouveaux r\u00e9seaux<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr5.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr5&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Expand-Open-Education-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color:#000;\"><span style=\"text-decoration: underline;\"><strong>\u00c9largir l\u2019\u00e9ducation ouverte<\/strong><\/span><\/a><br \/>\nAdaptez, adoptez et cr\u00e9ez des ressources \u00e9ducatives libres<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Full-Guide-Singles-fr6.png\u00a0\u00bb title_text=\u00a0\u00bbeCO-DxGuide-Full-Guide-Singles-fr6&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/eCO-DxGuide-Develop-Workforce-fr.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color:#000;\"><span style=\"text-decoration: underline;\"><strong>Perfectionner la main-d\u2019oeuvre de demain<\/strong><\/span><\/a><br \/>\nHarmonisez les nouveaux programmes avec les demandes du march\u00e9 du travail<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Ne manquez pas cette occasion! Contribuez d\u00e8s aujourd\u2019hui \u00e0 b\u00e2tir l\u2019avenir de l\u2019apprentissage num\u00e9rique. Explorez les programmes, les plateformes et les services d\u2019eCampusOntario qui vous aideront \u00e0 transformer l\u2019enseignement num\u00e9rique et l\u2019apprentissage dans votre \u00e9tablissement. D\u00e9finissez votre campus num\u00e9rique et suivez la transformation de l\u2019enseignement sup\u00e9rieur en Ontario. Explorez les possibilit\u00e9s offertes par eCampusOntario pour votre \u00e9tablissement.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<div class=\"_3d-flip-book  fb3d-fullscreen-mode full-size\" data-id=\"3604\" data-mode=\"fullscreen\" data-title=\"false\" data-template=\"short-white-book-view\" data-lightbox=\"dark-shadow\" data-urlparam=\"fb3d-page\" data-page-n=\"0\" data-pdf=\"\" data-tax=\"null\" data-thumbnail=\"\" data-cols=\"3\" data-book-template=\"default\" data-trigger=\"\"><\/div><script type=\"text\/javascript\">window.FB3D_CLIENT_DATA = window.FB3D_CLIENT_DATA || [];FB3D_CLIENT_DATA.push('eyJwb3N0cyI6eyIzNjA0Ijp7IklEIjozNjA0LCJ0aXRsZSI6IkRYIGZ1bGwgZ3VpZGUgRnJlbmNoIiwidHlwZSI6InBkZiIsInJlYWR5X2Z1bmN0aW9uIjoiIiwiYm9va19zdHlsZSI6ImZsYXQiLCJib29rX3RlbXBsYXRlIjoibm9uZSIsIm91dGxpbmUiOltdLCJkYXRhIjp7InBvc3RfSUQiOiIzNjA1IiwiZ3VpZCI6Imh0dHBzOlwvXC92bHMuZWNhbXB1c29udGFyaW8uY2FcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA1XC9lQ08tRHhHdWlkZS1GdWxsLUd1aWRlLVNpbmdsZXMtZnIucGRmIiwicGRmX3BhZ2VzIjoiMjUiLCJwYWdlc19jdXN0b21pemF0aW9uIjoibm9uZSJ9LCJ0aHVtYm5haWwiOnsiZGF0YSI6eyJwb3N0X0lEIjoiMCJ9LCJ0eXBlIjoiYXV0byJ9LCJwcm9wcyI6eyJjYWNoZWRQYWdlcyI6ImF1dG8iLCJyZW5kZXJJbmFjdGl2ZVBhZ2VzIjoiYXV0byIsInJlbmRlckluYWN0aXZlUGFnZXNPbk1vYmlsZSI6ImF1dG8iLCJyZW5kZXJXaGlsZUZsaXBwaW5nIjoiYXV0byIsInByZWxvYWRQYWdlcyI6ImF1dG8iLCJhdXRvUGxheUR1cmF0aW9uIjoiYXV0byIsInJ0bCI6ImF1dG8iLCJpbnRlcmFjdGl2ZUNvcm5lcnMiOiJhdXRvIiwic2hlZXQiOnsic3RhcnRWZWxvY2l0eSI6ImF1dG8iLCJ3YXZlIjoiYXV0byIsInNoYXBlIjoiYXV0byIsIndpZHRoVGV4ZWxzIjoiYXV0byIsImNvbG9yIjoiYXV0byIsInNpZGUiOiJhdXRvIiwiY29ybmVyRGV2aWF0aW9uIjoiYXV0byIsImZsZXhpYmlsaXR5IjoiYXV0byIsImZsZXhpYmxlQ29ybmVyIjoiYXV0byIsImJlbmRpbmciOiJhdXRvIiwiaGVpZ2h0VGV4ZWxzIjoiYXV0byJ9LCJjb3ZlciI6eyJ3YXZlIjoiYXV0byIsImNvbG9yIjoiYXV0byIsImJpbmRlclRleHR1cmUiOiJhdXRvIiwiZGVwdGgiOiJhdXRvIiwicGFkZGluZyI6ImF1dG8iLCJzdGFydFZlbG9jaXR5IjoiYXV0byIsImZsZXhpYmlsaXR5IjoiYXV0byIsImZsZXhpYmxlQ29ybmVyIjoiYXV0byIsImJlbmRpbmciOiJhdXRvIiwid2lkdGhUZXhlbHMiOiJhdXRvIiwiaGVpZ2h0VGV4ZWxzIjoiYXV0byIsIm1hc3MiOiJhdXRvIiwic2lkZSI6ImF1dG8iLCJzaGFwZSI6ImF1dG8ifSwicGFnZSI6eyJ3YXZlIjoiYXV0byIsImNvbG9yIjoiYXV0byIsImRlcHRoIjoiYXV0byIsInN0YXJ0VmVsb2NpdHkiOiJhdXRvIiwiZmxleGliaWxpdHkiOiJhdXRvIiwiZmxleGlibGVDb3JuZXIiOiJhdXRvIiwiYmVuZGluZyI6ImF1dG8iLCJ3aWR0aFRleGVscyI6ImF1dG8iLCJoZWlnaHRUZXhlbHMiOiJhdXRvIiwibWFzcyI6ImF1dG8iLCJzaWRlIjoiYXV0byIsInNoYXBlIjoiYXV0byJ9LCJoZWlnaHQiOiJhdXRvIiwid2lkdGgiOiJhdXRvIiwiZ3Jhdml0eSI6ImF1dG8iLCJwYWdlc0ZvclByZWRpY3RpbmciOiJhdXRvIn0sImNvbnRyb2xQcm9wcyI6eyJhY3Rpb25zIjp7ImNtZFRvYyI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8iLCJhY3RpdmUiOiJhdXRvIiwiZGVmYXVsdFRhYiI6ImF1dG8ifSwiY21kQXV0b1BsYXkiOnsiZW5hYmxlZCI6ImF1dG8iLCJlbmFibGVkSW5OYXJyb3ciOiJhdXRvIiwiYWN0aXZlIjoiYXV0byJ9LCJjbWRTYXZlIjp7ImVuYWJsZWQiOiJhdXRvIiwiZW5hYmxlZEluTmFycm93IjoiYXV0byJ9LCJjbWRQcmludCI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8ifSwiY21kU2luZ2xlUGFnZSI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8iLCJhY3RpdmUiOiJhdXRvIiwiYWN0aXZlRm9yTW9iaWxlIjoiYXV0byJ9LCJ3aWRUb29sYmFyIjp7ImVuYWJsZWQiOiJhdXRvIiwiZW5hYmxlZEluTmFycm93IjoiYXV0byJ9fX0sImF1dG9UaHVtYm5haWwiOiJodHRwczpcL1wvdmxzLmVjYW1wdXNvbnRhcmlvLmNhXC93cC1jb250ZW50XC91cGxvYWRzXC8zZC1mbGlwLWJvb2tcL2F1dG8tdGh1bWJuYWlsc1wvMzYwNC5wbmciLCJwb3N0X25hbWUiOiJkeC1mdWxsLWd1aWRlLWZyZW5jaCIsInBvc3RfdHlwZSI6IjNkLWZsaXAtYm9vayJ9fSwicGFnZXMiOltdLCJmaXJzdFBhZ2VzIjpbXX0=');window.FB3D_CLIENT_LOCALE && FB3D_CLIENT_LOCALE.render && FB3D_CLIENT_LOCALE.render();<\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb module_id=\u00a0\u00bboer\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FCB53B\u00a0\u00bb custom_padding=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb da_popup_slug=\u00a0\u00bboer\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||justify-content: center;||align-items:stretch;||flex-direction:column;||@media only screen and (min-width: 768px) {flex-direction:row;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-right:0px !important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/OpenLibrary-Icon.png\u00a0\u00bb title_text=\u00a0\u00bbOpenLibrary Icon\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb150px\u00a0\u00bb height=\u00a0\u00bb120px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;||    justify-content: center;||    align-items: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text content_tablet=\u00a0\u00bb<\/p>\n<h3 style=%22text-align: center;%22>Adopt Open Educational Resources<\/h3>\n<p>\u00a0\u00bb content_phone=\u00a0\u00bb<\/p>\n<h3 style=%22text-align: center;%22>Adopt Open Educational Resources<\/h3>\n<p>\u00a0\u00bb content_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_color=\u00a0\u00bb#000000&Prime; background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: left;\">Adoptez des ressources \u00e9ducatives libres<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La biblioth\u00e8que libre d\u2019eCampusOntario contient une multitude de ressources \u00e9ducatives libres (REL) de haute qualit\u00e9 qui n\u2019attendent que vous. Soumises \u00e0 une \u00e9valuation rigoureuse, les REL peuvent \u00eatre utilis\u00e9es telles quelles ou adapt\u00e9es pour r\u00e9pondre \u00e0 vos besoins d\u2019apprentissage particuliers.<\/p>\n<p>Pour une dur\u00e9e limit\u00e9e, les auteurs et les \u00e9quipes d\u2019auteurs peuvent recevoir des honoraires de 750 $ pour la modification de REL bas\u00e9e sur l\u2019\u00e9valuation par les pairs, tout en contribuant \u00e0 transformer le paysage de l\u2019apprentissage num\u00e9rique postsecondaire en Ontario. Les \u00e9ducateurs de l\u2019Ontario peuvent \u00e9galement b\u00e9n\u00e9ficier d\u2019honoraires de 300 $ s\u2019ils \u00e9valuent, conservent, adaptent et adoptent des REL pour les int\u00e9grer \u00e0 leur enseignement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<strong>Les d\u00e9tails complets du programme se trouvent en ligne sur cette nouvelle page Web :<\/strong>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/openlibrary.ecampusontario.ca\/fr\/integrating-oer-program\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bben savoir plus\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbec01e611-d518-43b0-a355-1f4a4b9c5b67&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb module_id=\u00a0\u00bbpd\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#7a9cb5&Prime; custom_padding=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb da_popup_slug=\u00a0\u00bbpd\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||justify-content: center;||align-items:stretch;||flex-direction:column;||@media only screen and (min-width: 768px) {flex-direction:row;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-right:0px !important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/06\/DX-Logo-2.png\u00a0\u00bb title_text=\u00a0\u00bbDX Logo\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb120px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;||    justify-content: center;||    align-items: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><span class=\"NormalTextRun SCXW192676592 BCX0\">Explorez un monde de possibilit\u00e9s gr\u00e2ce \u00e0 notre s\u00e9rie d\u2019apprentissages sur la transformation <\/span><span class=\"NormalTextRun SCXW192676592 BCX0\">num\u00e9rique.\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-contrast=\"none\">eCampusOntario vous invite \u00e0 perfectionner vos comp\u00e9tences num\u00e9riques, \u00e0 devenir un champion num\u00e9rique dans votre \u00e9tablissement et \u00e0 favoriser les cultures d\u2019innovation n\u00e9cessaires \u00e0 la transformation num\u00e9rique.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Lib\u00e9rez le potentiel de vos priorit\u00e9s en mati\u00e8re d\u2019apprentissage num\u00e9rique et entamez un parcours de croissance professionnelle. <\/span><span data-contrast=\"none\">Les programmes de perfectionnement professionnel d\u2019eCampusOntario sont con\u00e7us sp\u00e9cialement pour les \u00e9ducateurs qui cherchent \u00e0 d\u00e9velopper leurs capacit\u00e9s num\u00e9riques\u202f.<\/span><\/p>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Pour en savoir plus, consultez les d\u00e9tails complets de nos programmes de d\u00e9veloppement professionnel.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/learn.ecampusontario.ca\/?cm_locale=fr\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbEn savoir plus\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbleft\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbec01e611-d518-43b0-a355-1f4a4b9c5b67&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><b><span data-contrast=\"none\"><span class=\"ui-provider ee bpb bln cqy cqz cra crb crc crd cre crf crg crh cri crj crk crl crm crn cro crp crq crr crs crt cru crv crw crx cry crz csa csb csc csd\" dir=\"ltr\"><strong>P\u00e9dagogie num\u00e9rique certifi\u00e9e <\/strong><\/span>: Am\u00e9liorez votre r\u00e9f\u00e9rentiel p\u00e9dagogique <\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"o\" data-font=\"Courier New\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:1440,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Courier New&quot;,&quot;469769242&quot;:[9675],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;o&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"2\"><span data-contrast=\"none\">Gr\u00e2ce \u00e0 ce <\/span><b><span data-contrast=\"none\">programme de micro-titres de comp\u00e9tences+<\/span><\/b><span data-contrast=\"none\">, les \u00e9ducateurs des \u00e9tablissements postsecondaires explorent une gamme vari\u00e9e de technologies et de pratiques p\u00e9dagogiques pour <\/span><b><span data-contrast=\"none\">enseignement et apprentissage en ligne assist\u00e9s par la technologie<\/span><\/b><span data-contrast=\"none\"> \u2014 qu\u2019ils soient hybrides, comodaux ou enti\u00e8rement en ligne. Que vous souhaitiez d\u00e9velopper vos comp\u00e9tences num\u00e9riques ou simplement rester au fait des derni\u00e8res tendances en mati\u00e8re d\u2019\u00e9ducation, le programme de micro-titre de comp\u00e9tences+ <span class=\"ui-provider ee bpb bln cqy cqz cra crb crc crd cre crf crg crh cri crj crk crl crm crn cro crp crq crr crs crt cru crv crw crx cry crz csa csb csc csd\" dir=\"ltr\">P\u00e9dagogie num\u00e9rique certifi\u00e9e<\/span> est l\u00e0 pour vous accompagner. <\/span><i><span data-contrast=\"none\">Il s\u2019agit d\u2019un programme de micro-titre de comp\u00e9tences+\u202f: les personnes qui le terminent obtiennent des cr\u00e9dits accord\u00e9s en \u00e9quivalence du <\/span><\/i><a href=\"https:\/\/continuing-education.conestogac.on.ca\/programs\/post-secondary-teaching\"><i><span data-contrast=\"none\">certificat en enseignement postsecondaire au Coll\u00e8ge Conestoga<\/span><\/i><\/a><i><span data-contrast=\"none\">\u202f. <\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"none\">Leadership pour la transformation num\u00e9rique (Dx)\u202f: \u00catre un pionnier num\u00e9rique<\/span><\/b><span data-contrast=\"none\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Notre programme de micro-titres de comp\u00e9tences en leadership pour la transformation num\u00e9rique (Dx) dote les participants d\u2019outils, de connaissances et de ressources essentiels pour diriger et faciliter la transformation num\u00e9rique dans leurs \u00e9tablissements. Ouvert \u00e0 tous les dirigeants d\u2019\u00e9tablissements, ce programme outille les individus pour qu\u2019ils contribuent activement au parcours de la transformation num\u00e9rique et en fassent la promotion en veillant \u00e0 ce que les dipl\u00f4m\u00e9s canadiens soient bien pr\u00e9par\u00e9s pour l\u2019avenir du travail.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><b><span data-contrast=\"none\">Pr\u00e9parer les avenirs de l\u2019enseignement postsecondaire\u202f: Cr\u00e9er une capacit\u00e9 de prospective au sein de votre \u00e9quipe\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Nos ateliers de prospective sont con\u00e7us pour aider les \u00e9tablissements d\u2019enseignement sup\u00e9rieur \u00e0 imaginer, \u00e0 analyser et \u00e0 cr\u00e9er l\u2019avenir de l\u2019enseignement sup\u00e9rieur. On pr\u00e9sente souvent l\u2019avenir comme s\u2019il \u00e9tait pr\u00e9d\u00e9termin\u00e9 et pouvait \u00eatre pr\u00e9dit. Toutefois, la pratique de la prospective ne constitue pas de la pr\u00e9vision. Nous partons plut\u00f4t du principe que l\u2019avenir d\u00e9pend des choix faits aujourd\u2019hui et que de nombreuses perspectives diff\u00e9rentes sont possibles. Les participants seront initi\u00e9s \u00e0 la prospective et apprendront \u00e0 identifier les signes de changement dans le pr\u00e9sent pour extrapoler ce qui est possible dans l\u2019avenir.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb module_id=\u00a0\u00bbpd\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#7a9cb5&Prime; custom_padding=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb da_popup_slug=\u00a0\u00bbpd\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||justify-content: center;||align-items:stretch;||flex-direction:column;||@media only screen and (min-width: 768px) {flex-direction:row;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-right:0px !important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/Professional-Development-Icon.png\u00a0\u00bb title_text=\u00a0\u00bbProfessional Development Icon\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb150px\u00a0\u00bb height=\u00a0\u00bb120px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;||    justify-content: center;||    align-items: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Inscrivez-vous \u00e0 nos programmes pour am\u00e9liorer les comp\u00e9tences de vos professionnels<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Aidez vos chefs de file de l\u2019apprentissage num\u00e9rique \u00e0 se perfectionner en proc\u00e9dant au perfectionnement professionnel gratuit de vos \u00e9quipes acad\u00e9miques. Renforcez votre capacit\u00e9 de transformation de l\u2019apprentissage num\u00e9rique afin de surmonter les obstacles et de maintenir votre avantage en mati\u00e8re d\u2019apprentissage num\u00e9rique.<\/p>\n<p>eCampusOntario demande aux membres des \u00e9quipes acad\u00e9miques de toute la province d\u2019indiquer leur int\u00e9r\u00eat pour le micro-titre de comp\u00e9tences intitul\u00e9 \u00ab Leadership pour la transformation num\u00e9rique \u00bb. Le micro-titre de comp\u00e9tences offre une nouvelle possibilit\u00e9 de perfectionnement professionnel dans une s\u00e9rie de modules en ligne asynchrones et anim\u00e9s, avec des exp\u00e9riences d\u2019apprentissage, des outils et un accompagnement mobilisateurs pour faire avancer la transformation num\u00e9rique dans votre \u00e9tablissement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Contribuez \u00e0 fa\u00e7onner les chefs de file de la transformation num\u00e9rique et l\u2019apprentissage num\u00e9rique dans tout le secteur. Reconnaissez vos chefs de file et maintenez l\u2019\u00e9lan de l\u2019apprentissage num\u00e9rique de votre \u00e9tablissement.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/go.ecampusontario.ca\/l\/847833\/2023-03-07\/mtqt8&Prime; url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbIndiquez votre int\u00e9r\u00eat d\u00e8s aujourd\u2019hui\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbleft\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbec01e611-d518-43b0-a355-1f4a4b9c5b67&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb module_id=\u00a0\u00bbdiscover\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#1E1A34&Prime; custom_padding=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb da_popup_slug=\u00a0\u00bbdiscover\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay:flex;||justify-content: center;||align-items:stretch;||flex-direction:column;||@media only screen and (min-width: 768px) {flex-direction:row;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbmargin-right:0px !important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/Sandbox-icon.png\u00a0\u00bb title_text=\u00a0\u00bbSandbox-icon\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb150px\u00a0\u00bb height=\u00a0\u00bb120px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbdisplay: flex;||    justify-content: center;||    align-items: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bb8c6ed3ff-f576-46b6-bc4a-4774465316bf\u00a0\u00bb header_2_text_color=\u00a0\u00bb#1E1A34&Prime; header_3_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb20px|0px|20px|0px|true|true\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bb\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>D\u00e9couvrez, mettez \u00e0 l\u2019essai, \u00e9valuez et adoptez les technologies de l\u2019\u00e9ducation<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/dx-image.png\u00a0\u00bb title_text=\u00a0\u00bbdx-image\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>eCampusOntario aide les entreprises de technologie de l\u2019\u00e9ducation et de services connexes \u00e0 innover dans l\u2019enseignement sup\u00e9rieur dans des environnements d\u2019essai s\u00fbrs.<\/p>\n<p>Augmentez votre capacit\u00e9 d\u2019innovation.Explorez la liste du catalogue de technologies de l\u2019\u00e9ducation, demandez une d\u00e9monstration, \u00e9coutez et mobilisez-vous avec vos pairs pour \u00e9valuer l\u2019int\u00e9gration de la technologie dans vos exp\u00e9riences d\u2019apprentissage num\u00e9rique. Faites appel \u00e0 nos produits et services et faites-nous part de vos commentaires afin d\u2019adapter la recherche et l\u2019\u00e9laboration de produits de technologie de l\u2019\u00e9ducation et de simplifier l\u2019adoption d\u2019outils, de technologies et de services pour votre \u00e9tablissement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Entrez en contact avec des entreprises de technologies de l\u2019\u00e9ducation, collaborez avec d\u2019autres membres, d\u00e9couvrez des outils pour \u00e9valuer vos capacit\u00e9s et mettez ces derniers \u00e0 l\u2019essai pour enrichir vos exp\u00e9riences d\u2019apprentissage num\u00e9rique et faire progresser vos priorit\u00e9s num\u00e9riques.<\/p>\n<p><strong>Pour une dur\u00e9e limit\u00e9e, acc\u00e9dez \u00e0 des licences gratuites de technologies de l\u2019\u00e9ducation en vous inscrivant \u00e0 un essai. Rejoignez une communaut\u00e9 grandissante d\u2019experts en technologies de l\u2019\u00e9ducation pour explorer les possibilit\u00e9s offertes par ces technologies d\u00e8s aujourd\u2019hui .<\/strong>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/sandbox.ecampusontario.ca\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbVisitez ici\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbec01e611-d518-43b0-a355-1f4a4b9c5b67&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#D9D6E6&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2023\/05\/contact-us-icon.png\u00a0\u00bb title_text=\u00a0\u00bbcontact us-icon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFrutiger-Pro-Bold|900|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]BESOIN D&rsquo;AIDE ?[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFrutiger-Pro-Bold|900|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb36px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]eCampusOntario est l\u00e0 pour vous aider.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbeadb682f-24da-4a82-a21c-e870b2acf7e3&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Communiquez avec nous pour en savoir plus sur les services offerts.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<a data-toggle=\"modal\" data-bs-toggle=\"modal\" data-target=\"#frm-modal-0\" data-bs-target=\"#frm-modal-0\" href=\"#\" class=\"et_pb_button formidable-button et_pb_bg_layout_light\">Nous contacter<\/a>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#1e1a34&Prime; custom_padding=\u00a0\u00bb||2px|||\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_module=\u00a0\u00bb1991&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_6,1_6,1_6,1_6,1_6,1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb95%\u00a0\u00bb max_width=\u00a0\u00bb95%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2020\/11\/eco-wordmark-white.png\u00a0\u00bb alt=\u00a0\u00bbeCampusontario Logo\u00a0\u00bb title_text=\u00a0\u00bbeco-wordmark-white\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb width_phone=\u00a0\u00bb50%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/vls.ecampusontario.ca\/wp-content\/uploads\/2020\/11\/ontario-logo-1.png\u00a0\u00bb alt=\u00a0\u00bbOntario-Logo\u00a0\u00bb title_text=\u00a0\u00bbontario-logo (1)\u00a0\u00bb _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb width_phone=\u00a0\u00bb50%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb95%\u00a0\u00bb max_width=\u00a0\u00bb95%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.7.3&Prime; _module_preset=\u00a0\u00bb55b77ebb-b59f-4f8d-b74f-86272540b1a2&Prime; text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>eCampusOntario est un centre d\u2019excellence sans but lucratif et un chef de file mondial en mati\u00e8re d\u2019innovation en enseignement et en apprentissage par la technologie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.6.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; text_orientation=\u00a0\u00bbright\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb link_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/www.ecampusontario.ca\/accessibility-statement\/\" target=\"_blank\" rel=\"noopener\">D\u00e9claration sur l\u2019accessibilit\u00e9 <\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faites progresser votre transformation num\u00e9riqueLib\u00e9rez le potentiel de vos priorit\u00e9s en mati\u00e8re d\u2019apprentissage num\u00e9rique avec l\u2019aide d\u2019eCampusOntario. L\u2019avenir de l\u2019apprentissage num\u00e9rique est \u00e0 nos portes. Innovez gr\u00e2ce aux ressources gratuites offertes par eCampusOntario.Les \u00e9tablissements d\u2019enseignement sup\u00e9rieur de l\u2019Ontario ont r\u00e9agi d\u00e8s le d\u00e9but de la pand\u00e9mie en passant des salles de classe en personne \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3172,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-3388","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/pages\/3388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/comments?post=3388"}],"version-history":[{"count":35,"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/pages\/3388\/revisions"}],"predecessor-version":[{"id":3746,"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/pages\/3388\/revisions\/3746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/media\/3172"}],"wp:attachment":[{"href":"https:\/\/vls.ecampusontario.ca\/fr\/wp-json\/wp\/v2\/media?parent=3388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}